{"id":99619,"date":"2025-02-27T05:02:50","date_gmt":"2025-02-27T12:02:50","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/2025\/02\/27\/lustre-girls-lose-to-circle\/?destination=northern-plains-independent"},"modified":"2025-02-27T05:11:29","modified_gmt":"2028-01-13T05:11:29","slug":"lustre-girls-lose-to-circle","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2025\/02\/27\/lustre-girls-lose-to-circle\/?destination=northern-plains-independent","title":{"rendered":"Lustre Girls Lose To Circle"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Lustre\u2019s girls\u2019 basketball team lost to Circle by a 61-6 final during loser-out play at the District 3C tournament held in Wolf Point.<br \/>\n\t  The Wildcats jumped out to a 26-4 lead in the first quarter  and held a 39-6 half-time advantage.<br \/>\n\t  Circle led with a 53-6 advantage at the end of the third quarter.<br \/>\n\t  Scoring for the Lions were Lauryn Holzrichter with four and Sidney Klatt with two points.<\/p>\n","protected":false},"author":1,"featured_media":99610,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/99619"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=99619"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/99619\/revisions"}],"predecessor-version":[{"id":99721,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/99619\/revisions\/99721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media\/99610"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=99619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=99619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=99619"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=99619"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=99619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}