{"id":96205,"date":"2025-01-02T05:02:20","date_gmt":"2025-01-02T12:02:20","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/2025\/01\/02\/senior-news-20250101-0923-205622\/?destination=northern-plains-independent"},"modified":"2025-01-02T05:09:47","modified_gmt":"2027-11-18T05:09:47","slug":"senior-news-20250101-0923-205622","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2025\/01\/02\/senior-news-20250101-0923-205622\/?destination=northern-plains-independent","title":{"rendered":"Senior News"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Roosevelt County Aging Services wants to let seniors know about some Medicare Helping Programs.<br \/>\n\t  There is Social Security Extra Help, which helps with the cost of your Medicare part D prescription costs. The income limit for Extra Help is $22,830 for a single  person or $30,900 for a couple. The asset limit for a single person is up to $17,220 or $34,360 for a couple. Your home, vehicle and personal<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/96205"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=96205"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/96205\/revisions"}],"predecessor-version":[{"id":96275,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/96205\/revisions\/96275"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=96205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=96205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=96205"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=96205"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=96205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}