{"id":92135,"date":"2024-10-31T05:05:10","date_gmt":"2024-10-31T11:05:10","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/2024\/10\/31\/smith-taylor-seek-house-district-seat\/?destination=northern-plains-independent"},"modified":"2024-10-31T05:17:13","modified_gmt":"2027-04-19T05:17:13","slug":"smith-taylor-seek-house-district-seat","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2024\/10\/31\/smith-taylor-seek-house-district-seat\/?destination=northern-plains-independent","title":{"rendered":"Smith, Taylor Seek  House District Seat"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Area voters will have a choice to make between a long-time legislator and a political  newcomer in the election  for House District 31.<br \/>\n\t  Republican Kevin Taylor is challenging incumbent Frank Smith in the Nov. 5 election.<br \/>\n\t  Taylor, who lives just outside  of Glasgow, said it\u2019s up to the voters if they want someone  with fresh eyes and fresh ears in the state legislature.<br \/>\n\t  \u201cIt\u2019s going<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/92135"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=92135"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/92135\/revisions"}],"predecessor-version":[{"id":92299,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/92135\/revisions\/92299"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=92135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=92135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=92135"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=92135"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=92135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}