{"id":9190,"date":"2020-04-09T05:00:40","date_gmt":"2020-04-09T11:00:40","guid":{"rendered":"https:\/\/uswps02.newsmemory.com\/northernplainsindependent\/news\/?p=9190?destination=northern-plains-independent"},"modified":"2020-04-09T05:04:25","modified_gmt":"2020-04-09T11:04:25","slug":"lucky-clovers-reach-out-to-area-residents","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2020\/04\/09\/lucky-clovers-reach-out-to-area-residents\/?destination=northern-plains-independent","title":{"rendered":"Lucky Clovers Reach Out To Area Residents"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Valley County Extension agent Roubie Younkin told the  Northern Plains Independent that members of the Lucky Clover 4-H club in Fort Peck and Nashua have been mailing cards to area residents who may be feeling the effects of social isolation.<br \/>\n\t  According to Younkin, there are 18 members  in the club. She said all 18 kids made cards. She doesn\u2019t know what messages they contained.<br \/>\n\t  \u201cI\u2019m afraid<\/p>\n","protected":false},"author":1,"featured_media":9239,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/9190"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=9190"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/9190\/revisions"}],"predecessor-version":[{"id":9224,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/9190\/revisions\/9224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media\/9239"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=9190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=9190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=9190"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=9190"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=9190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}