{"id":89318,"date":"2024-09-19T05:05:20","date_gmt":"2024-09-19T11:05:20","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/2024\/09\/19\/judge-hears-petition-to-revoke-cases\/?destination=northern-plains-independent"},"modified":"2024-09-19T05:16:48","modified_gmt":"2027-03-08T05:16:48","slug":"judge-hears-petition-to-revoke-cases","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2024\/09\/19\/judge-hears-petition-to-revoke-cases\/?destination=northern-plains-independent","title":{"rendered":"Judge Hears Petition To Revoke Cases"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Several petition to revoke cases were conducted in district court in front of District  Judge David Cybulski on Wednesday, Sept. 11.<br \/>\n\t  Trevor Levi Crain changed his plea and admitted to not reporting an instance of failure  to comply with the law.<br \/>\n\t  Based on a joint recommendation,  Cybulski unsuspended  Crain\u2019s 10-year sentence  with the Department of Corrections for Crain to receive treatment.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/89318"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=89318"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/89318\/revisions"}],"predecessor-version":[{"id":89469,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/89318\/revisions\/89469"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=89318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=89318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=89318"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=89318"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=89318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}