{"id":87759,"date":"2024-08-29T05:01:50","date_gmt":"2024-08-29T11:01:50","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/2024\/08\/29\/lustre-looks-to-improve-during-volleyball-season\/?destination=northern-plains-independent"},"modified":"2024-09-13T15:38:39","modified_gmt":"2027-03-02T15:38:39","slug":"lustre-looks-to-improve-during-volleyball-season","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2024\/08\/29\/lustre-looks-to-improve-during-volleyball-season\/?destination=northern-plains-independent","title":{"rendered":"Lustre Looks To Improve During Volleyball Season"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>The Lustre Lions will rely on some new faces on their high school volleyball team to have a good season this year.<br \/>\n\t  The Lions do have four starters back including senior  Abby Olfert, senior Jaden Gibson, junior Hannah Brown and sophomore Lauryn Holzrichter.<br \/>\n\t  Other seniors on the team are Rachel Pew and Katie Calderone.<br \/>\n\t  Coach Mary Zerbe is excited to have seven freshmen on the squad.<\/p>\n","protected":false},"author":1,"featured_media":87751,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/87759"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=87759"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/87759\/revisions"}],"predecessor-version":[{"id":88029,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/87759\/revisions\/88029"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media\/87751"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=87759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=87759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=87759"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=87759"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=87759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}