{"id":85907,"date":"2024-08-01T05:01:40","date_gmt":"2024-08-01T11:01:40","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/2024\/08\/01\/guiding-principles-for-mule-deer-management-plan-in-state\/?destination=northern-plains-independent"},"modified":"2024-09-13T15:39:07","modified_gmt":"2027-03-02T15:39:07","slug":"guiding-principles-for-mule-deer-management-plan-in-state","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2024\/08\/01\/guiding-principles-for-mule-deer-management-plan-in-state\/?destination=northern-plains-independent","title":{"rendered":"Guiding Principles For Mule  Deer Management Plan In State"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Montana Fish, Wildlife and Parks is looking for public feedback on work from a citizen  advisory council tasked with developing guiding principles for developing a new Mule Deer Management Plan.<br \/>\n\t  \u201cWe know how concerned people are with mule deer numbers across the state,\u201d said FWP director Dustin Temple. \u201cOur focus is developing  a new plan that will guide our efforts to manage herds well into<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/85907"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=85907"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/85907\/revisions"}],"predecessor-version":[{"id":86101,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/85907\/revisions\/86101"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=85907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=85907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=85907"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=85907"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=85907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}