{"id":78013,"date":"2024-03-28T05:01:40","date_gmt":"2024-03-28T11:01:40","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/2024\/03\/28\/poplar-track-enjoys-good-turnout-for-season\/?destination=northern-plains-independent"},"modified":"2024-09-13T15:40:56","modified_gmt":"2027-03-02T15:40:56","slug":"poplar-track-enjoys-good-turnout-for-season","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2024\/03\/28\/poplar-track-enjoys-good-turnout-for-season\/?destination=northern-plains-independent","title":{"rendered":"Poplar Track Enjoys Good Turnout For Season"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>With more than 30 athletes out for the sport, the Poplar Indians are looking forward to this track season.<br \/>\n\t  \u201cWe lost a bunch from last year,\u201d Poplar Coach Loren Boadle  said. \u201cWe\u2019re really young. We have a lot of freshmen.\u201d<br \/>\n\t  Senior Kessee Erickson highlights  Poplar\u2019s list of returning athletes. Erickson placed third at last year\u2019s divisional meet in the discus to qualify for the<\/p>\n","protected":false},"author":1,"featured_media":78003,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[13],"news-source":[12],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/78013"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=78013"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/78013\/revisions"}],"predecessor-version":[{"id":78294,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/78013\/revisions\/78294"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media\/78003"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=78013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=78013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=78013"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=78013"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=78013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}