{"id":74289,"date":"2024-01-25T05:02:40","date_gmt":"2024-01-25T12:02:40","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/2024\/01\/25\/cowgirls-drop-home-contest\/?destination=northern-plains-independent"},"modified":"2024-09-13T15:42:00","modified_gmt":"2027-03-02T15:42:00","slug":"cowgirls-drop-home-contest","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2024\/01\/25\/cowgirls-drop-home-contest\/?destination=northern-plains-independent","title":{"rendered":"Cowgirls Drop Home Contest"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Culbertson\u2019s girls\u2019 basketball  squad enjoyed a solid start, but the Cowgirls lost to Richey\/Lambert, 47-40, at home on Thursday, Jan. 18.<br \/>\n\t  The Cowgirls jumped out to a 17-6 advantage in the first quarter. A three-point shot by Destiny Thompson and a three-point play by Mariana Burciaga got the Cowgirls off to a 6-2 start.<br \/>\n\t  Ivy Colvin then scored off a great pass from Leandra Perkins  for<\/p>\n","protected":false},"author":1,"featured_media":74281,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"news-destination":[13],"news-source":[12],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/74289"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=74289"}],"version-history":[{"count":2,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/74289\/revisions"}],"predecessor-version":[{"id":74597,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/74289\/revisions\/74597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media\/74281"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=74289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=74289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=74289"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=74289"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=74289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}