{"id":71892,"date":"2023-12-14T05:07:40","date_gmt":"2023-12-14T12:07:40","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/2023\/12\/14\/wolf-point-police-blotter-20231213-0436-460845\/?destination=northern-plains-independent"},"modified":"2024-09-13T15:42:42","modified_gmt":"2027-03-02T15:42:42","slug":"wolf-point-police-blotter-20231213-0436-460845","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2023\/12\/14\/wolf-point-police-blotter-20231213-0436-460845\/?destination=northern-plains-independent","title":{"rendered":"Wolf Point Police Blotter"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>( Publisher\u2019s Note:  The following blotter includes the activities of the Wolf Point police and fire department Dec. 7-10. All those cited or arrested are presumed innocent.)<br \/>\n\tDecember 7<br \/>\n\t Jalen Arseneault, 25, male, 200 block of Johnson Street, partner\/family member assault, tribal court.<br \/>\n\tDecember 8<br \/>\n\t Fourteen-year-old female, 300 block of Knapp Street, criminal mischief, simple assault, disorderly<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/71892"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=71892"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/71892\/revisions"}],"predecessor-version":[{"id":72001,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/71892\/revisions\/72001"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=71892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=71892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=71892"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=71892"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=71892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}