{"id":71886,"date":"2023-12-14T05:08:20","date_gmt":"2023-12-14T12:08:20","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/2023\/12\/14\/poplar-celebrates-with-christmas-stroll-event\/?destination=northern-plains-independent"},"modified":"2024-09-13T15:42:41","modified_gmt":"2027-03-02T15:42:41","slug":"poplar-celebrates-with-christmas-stroll-event","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2023\/12\/14\/poplar-celebrates-with-christmas-stroll-event\/?destination=northern-plains-independent","title":{"rendered":"Poplar Celebrates With  Christmas Stroll Event"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Poplar welcomed the holiday season with a Christmas Stroll on Friday, Dec. 8. A highlight was the Northeast Montana Health Services Charitable Foundation holding a Festival of Trees fundraiser during Independence Bank\u2019s open house.<br \/>\n\t  Brandi Wilkinson, executive director of the foundation, was pleased that Poplar\u2019s Festival of Trees featured 12 entries compared to last year\u2019s total of nine.<\/p>\n","protected":false},"author":1,"featured_media":71865,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/71886"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=71886"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/71886\/revisions"}],"predecessor-version":[{"id":72108,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/71886\/revisions\/72108"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media\/71865"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=71886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=71886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=71886"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=71886"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=71886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}