{"id":63888,"date":"2023-08-03T05:00:10","date_gmt":"2023-08-03T11:00:10","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/?p=63888?destination=northern-plains-independent"},"modified":"2024-09-13T15:45:23","modified_gmt":"2027-03-02T15:45:23","slug":"a-series-of","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2023\/08\/03\/a-series-of\/?destination=northern-plains-independent","title":{"rendered":"\u2022  A series of &#8230;."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>\u2022  A series of tidal waves strike the western coast of Korea on Aug. 15. At least 346 people are killed and an additional  1,000 are considered missing after 25,000 homes are submerged in waves and flooding.<br \/>\n\t \u2022 Thousands of Canadians lose their savings when the Home Bank of Canada closes its doors on Aug. 17.<br \/>\n\t \u2022 Ada Delutuk Blackjack is rescued on Aug. 19 after being  marooned on Wrangel<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/63888"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=63888"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/63888\/revisions"}],"predecessor-version":[{"id":63912,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/63888\/revisions\/63912"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=63888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=63888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=63888"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=63888"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=63888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}