{"id":63844,"date":"2023-08-03T05:01:20","date_gmt":"2023-08-03T11:01:20","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/?p=63844?destination=northern-plains-independent"},"modified":"2024-09-13T15:45:21","modified_gmt":"2027-03-02T15:45:21","slug":"lustre-news-20230802-0353-570337","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2023\/08\/03\/lustre-news-20230802-0353-570337\/?destination=northern-plains-independent","title":{"rendered":"Lustre News"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Annual cleanup day at Lustre  Christian High School was on Monday, July 31. All those who assisted were greatly appreciated.<br \/>\n\t  Thirty men attended the annual Men\u2019s Camp-out on Saturday, July 22, at Fort Peck, sponsored by the Mennonite Brethren Church of Lustre. Guest speaker was Daryl Toews.<br \/>\n\t  Sunday, July 23, was a very special day for the MB Church. They had their service  at the Downstream<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/63844"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=63844"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/63844\/revisions"}],"predecessor-version":[{"id":63946,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/63844\/revisions\/63946"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=63844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=63844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=63844"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=63844"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=63844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}