{"id":63697,"date":"2023-08-03T05:01:10","date_gmt":"2023-08-03T11:01:10","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/?p=63697?destination=northern-plains-independent"},"modified":"2024-09-13T15:45:21","modified_gmt":"2027-03-02T15:45:21","slug":"tribes-mail-carriers-visit-with-smokey","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2023\/08\/03\/tribes-mail-carriers-visit-with-smokey\/?destination=northern-plains-independent","title":{"rendered":"Tribes, Mail Carriers Visit With Smokey"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Tribal officials on the Fort Peck Reservation gathered last week at council chambers  to show their support for Smokey Bear\u2019s messaging about fire safety, following a spring with warmer than average weather.  Located on more than two million acres, the Fort Peck Assiniboine and Sioux Tribes share a tribal government that provides services to area residents, including wildfire prevention efforts.<\/p>\n","protected":false},"author":1,"featured_media":63678,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[13],"news-source":[12],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/63697"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=63697"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/63697\/revisions"}],"predecessor-version":[{"id":63942,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/63697\/revisions\/63942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media\/63678"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=63697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=63697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=63697"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=63697"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=63697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}