{"id":6364,"date":"2020-03-05T05:04:30","date_gmt":"2020-03-05T12:04:30","guid":{"rendered":"http:\/\/uswps02.newsmemory.com\/northernplainsindependent\/news\/?p=6364?destination=northern-plains-independent"},"modified":"2020-03-11T14:25:14","modified_gmt":"2020-03-11T20:25:14","slug":"wolf-point-police-fire-b-20200304151504","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2020\/03\/05\/wolf-point-police-fire-b-20200304151504\/?destination=northern-plains-independent","title":{"rendered":"Wolf Point Police &amp; Fire Blotter"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>(Publisher\u2019s Note:  The following blotter includes the activities of the Wolf Point police and fire department Feb. 24 through March 1. All those cited or arrested are presumed innocent.)  Citations were issued to:<br \/>\n\tFebruary 24<br \/>\n\t Aaron Battiest, 20, male, 100 block of Benton Street, warrant, tribal court.<br \/>\n\tFebruary 25<br \/>\n\t Jayda Jackson, 23, female, 100 block of Third Avenue South, public<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/6364"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=6364"}],"version-history":[{"count":4,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/6364\/revisions"}],"predecessor-version":[{"id":7377,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/6364\/revisions\/7377"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=6364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=6364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=6364"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=6364"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=6364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}