{"id":62964,"date":"2023-07-20T05:07:10","date_gmt":"2023-07-20T11:07:10","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/?p=62964?destination=northern-plains-independent"},"modified":"2024-09-13T15:45:32","modified_gmt":"2027-03-02T15:45:32","slug":"senior-news-20230719-0351-306085","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2023\/07\/20\/senior-news-20230719-0351-306085\/?destination=northern-plains-independent","title":{"rendered":"Senior News"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Does Medicare cover me if I travel outside the United  States? Original Medicare covers all 50 States as well as the District of Columbia, U.S. territories American Samoa, Guam, the Northern Mariana Islands, Puerto Rico and the U.S. Virgin Islands.<br \/>\n\t  Medicare does not provide coverage outside the U.S. and its territories unless it is an emergency.<br \/>\n\t  On cruise ships, you will have Medicare coverage<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/62964"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=62964"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/62964\/revisions"}],"predecessor-version":[{"id":63161,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/62964\/revisions\/63161"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=62964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=62964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=62964"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=62964"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=62964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}