{"id":62880,"date":"2023-07-20T05:03:50","date_gmt":"2023-07-20T11:03:50","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/?p=62880?destination=northern-plains-independent"},"modified":"2024-09-13T15:45:34","modified_gmt":"2027-03-02T15:45:34","slug":"senior-menus-20230719-0349-522700","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2023\/07\/20\/senior-menus-20230719-0349-522700\/?destination=northern-plains-independent","title":{"rendered":"Senior  Menus"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Culbertson  July 21:  Hamburgers, fries, vegetable and dessert.<br \/>\n\t July 25:  French dip sandwiches,  baked potato, vegetable and dessert.<br \/>\n\t July 28:  Tator tot casserole, vegetable and dessert.<br \/>\n\t ***  Bainville  July 20:  Pork roast, mashed potatoes, vegetable and dessert.<br \/>\n\t July 25:  Chicken pot pie, coleslaw and dessert.<br \/>\n\t July 27:  Hamburger steak, mashed potatoes, vegetable and dessert.  ***<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"news-destination":[13],"news-source":[12],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/62880"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=62880"}],"version-history":[{"count":2,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/62880\/revisions"}],"predecessor-version":[{"id":63241,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/62880\/revisions\/63241"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=62880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=62880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=62880"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=62880"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=62880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}