{"id":61723,"date":"2023-06-29T05:04:10","date_gmt":"2023-06-29T11:04:10","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/?p=61723?destination=northern-plains-independent"},"modified":"2024-09-13T15:46:03","modified_gmt":"2027-03-02T15:46:03","slug":"research-day-includes-information-about-grasshoppers","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2023\/06\/29\/research-day-includes-information-about-grasshoppers\/?destination=northern-plains-independent","title":{"rendered":"Research Day Includes Information About Grasshoppers"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Dave Branson, research entomologist  for USDA-ARS in Sidney, provided an insight into the grasshopper  outbreaks and management during the Froid Research Farm Field Day on Thursday, June 22.<br \/>\n\t  Branson noted that eastern Montana  has experienced extensive outbreaks of grasshoppers in the last two years and this looks like another challenging year of dealing  with the pests. Branson said large amount<\/p>\n","protected":false},"author":1,"featured_media":61714,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[13],"news-source":[12],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/61723"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=61723"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/61723\/revisions"}],"predecessor-version":[{"id":61985,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/61723\/revisions\/61985"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media\/61714"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=61723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=61723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=61723"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=61723"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=61723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}