{"id":60326,"date":"2023-06-01T05:01:30","date_gmt":"2023-06-01T11:01:30","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/?p=60326?destination=northern-plains-independent"},"modified":"2024-09-13T15:46:44","modified_gmt":"2027-03-02T15:46:44","slug":"culbertson-rodeo-to-feature-womens-ranch-bronc-riding","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2023\/06\/01\/culbertson-rodeo-to-feature-womens-ranch-bronc-riding\/?destination=northern-plains-independent","title":{"rendered":"Culbertson Rodeo To Feature  Women\u2019s Ranch Bronc Riding"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>The Culbertson Rodeo is back again June 9-10 at the saddle club arena, this time offering women\u2019s bronc riding  Friday and Saturday.<br \/>\n\t  Organizers are seeking volunteers  to help staff evening food service.<br \/>\n\t  Featured events include bull riding, bareback, calf roping, saddle bronc, steer wrestling, barrel racing, team roping, ladies breakaway, junior  barrels and junior breakaway  and senior mens<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"news-destination":[13],"news-source":[12],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/60326"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=60326"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/60326\/revisions"}],"predecessor-version":[{"id":60499,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/60326\/revisions\/60499"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=60326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=60326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=60326"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=60326"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=60326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}