{"id":59530,"date":"2023-05-18T05:05:40","date_gmt":"2023-05-18T11:05:40","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/?p=59530?destination=northern-plains-independent"},"modified":"2024-09-13T15:46:58","modified_gmt":"2027-03-02T15:46:58","slug":"wolf-point-students-looking-ahead-with-dual-credit-classes","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2023\/05\/18\/wolf-point-students-looking-ahead-with-dual-credit-classes\/?destination=northern-plains-independent","title":{"rendered":"Wolf Point Students Looking Ahead With Dual Credit Classes"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Wolf Point High School is seeing a continued increase of students taking dual credit classes again this school year.<br \/>\n\t  \u201cIt has continued to grow over the last few years,\u201d Wolf Point High School counselor  Erin Loendorf said. \u201cWe are thankful for the on-going partnership with the college to provide an opportunity for our schools.\u201d<br \/>\n\t  In the 2022-2023 academic year: 27 seniors and 21 juniors<\/p>\n","protected":false},"author":1,"featured_media":59527,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/59530"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=59530"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/59530\/revisions"}],"predecessor-version":[{"id":59746,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/59530\/revisions\/59746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media\/59527"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=59530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=59530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=59530"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=59530"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=59530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}