{"id":58049,"date":"2023-04-20T05:01:00","date_gmt":"2023-04-20T11:01:00","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/?p=58049?destination=northern-plains-independent"},"modified":"2024-09-13T15:47:35","modified_gmt":"2027-03-02T15:47:35","slug":"library-board-talks-coding-kits-book-talks-20230419-0337-332803","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2023\/04\/20\/library-board-talks-coding-kits-book-talks-20230419-0337-332803\/?destination=northern-plains-independent","title":{"rendered":"Library Board Talks Coding Kits, Book Talks"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>The Roosevelt County Library  board held its regular meeting March 25.<br \/>\n\t  Attendees included Roosevelt  County Library acting chair Joyce Harvey, trustees Helen Welte, Perry Lilley Sr. and Vernie Madison, Froid Library director Sheri Harvey  and Roosevelt County Library director Janet Livingston.<br \/>\n\t  The purchases for surveillance  cameras were the only non-ordinary purchases. The last of the security<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/58049"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=58049"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/58049\/revisions"}],"predecessor-version":[{"id":58079,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/58049\/revisions\/58079"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=58049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=58049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=58049"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=58049"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=58049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}