{"id":56007,"date":"2023-03-23T05:07:10","date_gmt":"2023-03-23T11:07:10","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/?p=56007?destination=northern-plains-independent"},"modified":"2024-09-13T15:48:12","modified_gmt":"2027-03-02T15:48:12","slug":"nicholson-provides-positive-message-at-schools","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2023\/03\/23\/nicholson-provides-positive-message-at-schools\/?destination=northern-plains-independent","title":{"rendered":"Nicholson Provides Positive Message At Schools"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Motivational speaker Kasey  \u201cRezzalicious\u201d Nicholson provided inspiring messages during presentations in Wolf Point schools on Tuesday, March 14.<br \/>\n\t  Nicholson, who is originally  from Billings, is a wellness educator and rising comedian  in Indian Country. He has earned a bachelor\u2019s degree in health and human development  and a master\u2019s degree in mental health and rehabilitation.<br \/>\n\t  He believes<\/p>\n","protected":false},"author":1,"featured_media":56136,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/56007"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=56007"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/56007\/revisions"}],"predecessor-version":[{"id":56140,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/56007\/revisions\/56140"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media\/56136"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=56007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=56007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=56007"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=56007"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=56007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}