{"id":55974,"date":"2023-03-23T05:01:30","date_gmt":"2023-03-23T11:01:30","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/?p=55974?destination=northern-plains-independent"},"modified":"2024-09-13T15:48:18","modified_gmt":"2027-03-02T15:48:18","slug":"humanities-montana-funds-fort-peck-stories","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2023\/03\/23\/humanities-montana-funds-fort-peck-stories\/?destination=northern-plains-independent","title":{"rendered":"Humanities Montana Funds Fort Peck Stories"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Humanities Montana recently  awarded $42,367 to humanities projects across the state, including First Voices\u2019  Three Fort Peck Stories:  Assiniboine, Chippewa, and Sioux.<br \/>\n\t First Voices is a digital storytelling project working with students at reservation high schools and Tribal colleges  to create digital performances  of ancestral stories  that are published on an online portal. Students will<\/p>\n","protected":false},"author":1,"featured_media":55962,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[13],"news-source":[12],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/55974"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=55974"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/55974\/revisions"}],"predecessor-version":[{"id":56161,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/55974\/revisions\/56161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media\/55962"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=55974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=55974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=55974"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=55974"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=55974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}