{"id":53004,"date":"2023-02-09T05:04:40","date_gmt":"2023-02-09T12:04:40","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/?p=53004?destination=northern-plains-independent"},"modified":"2024-09-13T15:49:37","modified_gmt":"2027-03-02T15:49:37","slug":"commissioners-debate-county-road-resolution","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2023\/02\/09\/commissioners-debate-county-road-resolution\/?destination=northern-plains-independent","title":{"rendered":"Commissioners Debate  County Road Resolution"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Roosevelt County commissioners approved 18 of 19 resolutions to declare  the existence of several county  roads during their regular meeting  on Tuesday, Jan. 31.<br \/>\n\t  The resolution voted down by a 2-1 margin was 2023-74, which dealt with Road 1017.<br \/>\n\t  Commissioner Robert Toavs said he had concerns because some of the road, but not all of the road, has an easement to state land. County Attorney Frank<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[13],"news-source":[12],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/53004"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=53004"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/53004\/revisions"}],"predecessor-version":[{"id":53269,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/53004\/revisions\/53269"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=53004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=53004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=53004"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=53004"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=53004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}