{"id":52247,"date":"2023-01-26T05:08:30","date_gmt":"2023-01-26T12:08:30","guid":{"rendered":"https:\/\/www-northernplainsindependent-com-uswp*.sitenm.com\/?p=52247?destination=northern-plains-independent"},"modified":"2024-09-13T15:49:50","modified_gmt":"2027-03-02T15:49:50","slug":"wolf-point-police-blotter-20230125-0444-473948","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2023\/01\/26\/wolf-point-police-blotter-20230125-0444-473948\/?destination=northern-plains-independent","title":{"rendered":"Wolf Point Police Blotter"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>( Publisher\u2019s Note:  The following blotter includes the activities of the Wolf Point police and fire departments Jan. 16-22. All those cited or arrested are presumed innocent.)<br \/>\n\tJanuary 15<br \/>\n\t Sixteen-year-old male, 400 block of Fairweather Street, cruelty to animals, tribal court.<br \/>\n\tJanuary 16<br \/>\n\t Thomas Martell Sr., 32, male, 600 block of U.S. Highway  2 West, carrying concealed  dangerous weapon,<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/52247"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=52247"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/52247\/revisions"}],"predecessor-version":[{"id":52521,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/52247\/revisions\/52521"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=52247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=52247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=52247"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=52247"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=52247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}