{"id":49957,"date":"2022-12-29T05:02:30","date_gmt":"2022-12-29T12:02:30","guid":{"rendered":"https:\/\/www-northernplainsindependent-com-uswp*.sitenm.com\/?p=49957?destination=northern-plains-independent"},"modified":"2024-09-13T15:50:33","modified_gmt":"2027-03-02T15:50:33","slug":"frazer-girls-outscore-brockton-62-44","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2022\/12\/29\/frazer-girls-outscore-brockton-62-44\/?destination=northern-plains-independent","title":{"rendered":"Frazer Girls Outscore Brockton, 62-44"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>The Frazer Bearcubs enjoyed  a big offensive night and won at Brockton by a 62-44 final during girls\u2019 basketball  action on Wednesday, Dec. 21.<br \/>\n\t  Angel Nelligan had an incredible  game with 36 points for the Bearcubs. She hit three three-pointers during the contest.<br \/>\n\t Angeline White also reached double figures with 10 points.<br \/>\n\t  Others scoring for Frazer  included Audrey Smoker with six and Leigha<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/49957"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=49957"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/49957\/revisions"}],"predecessor-version":[{"id":50042,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/49957\/revisions\/50042"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=49957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=49957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=49957"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=49957"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=49957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}