{"id":49861,"date":"2022-12-29T05:01:40","date_gmt":"2022-12-29T12:01:40","guid":{"rendered":"https:\/\/www-northernplainsindependent-com-uswp*.sitenm.com\/?p=49861?destination=northern-plains-independent"},"modified":"2024-09-13T15:50:34","modified_gmt":"2027-03-02T15:50:34","slug":"community-pond-grant-money-available","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2022\/12\/29\/community-pond-grant-money-available\/?destination=northern-plains-independent","title":{"rendered":"Community Pond Grant Money Available"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Groups or individuals interested  in constructing or improving a community fishing  pond have until Feb. 1 to apply for a Montana Fish, Wildlife &amp;  Parks\u2019 Community  Pond Program grant. The objective of the Community Pond Program is to enhance public fishing opportunities in or near Montana communities  by providing funding that may be used to construct or improve a public fishing pond.<br \/>\n\t  Applicants<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[13],"news-source":[12],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/49861"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=49861"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/49861\/revisions"}],"predecessor-version":[{"id":50031,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/49861\/revisions\/50031"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=49861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=49861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=49861"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=49861"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=49861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}