{"id":49622,"date":"2022-12-22T05:06:20","date_gmt":"2022-12-22T12:06:20","guid":{"rendered":"https:\/\/www-northernplainsindependent-com-uswp*.sitenm.com\/?p=49622?destination=northern-plains-independent"},"modified":"2024-09-13T15:50:40","modified_gmt":"2027-03-02T15:50:40","slug":"senior-menus-20221221-0455-109486","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2022\/12\/22\/senior-menus-20221221-0455-109486\/?destination=northern-plains-independent","title":{"rendered":"Senior  Menus"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Wolf Point  Congregate Meals  Dec. 22:  Chicken cordon bleu, squash, jello salad and dessert.<br \/>\n\t Dec. 27:  Chicken noodle soup, corn bread and dessert.<br \/>\n\t Dec. 29:  Ham, scalloped potatoes, Asian vegetables, birthday cake and ice cream.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/49622"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=49622"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/49622\/revisions"}],"predecessor-version":[{"id":49791,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/49622\/revisions\/49791"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=49622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=49622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=49622"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=49622"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=49622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}