{"id":47222,"date":"2022-11-03T05:02:30","date_gmt":"2022-11-03T11:02:30","guid":{"rendered":"https:\/\/www-northernplainsindependent-com-uswp*.sitenm.com\/?p=47222?destination=northern-plains-independent"},"modified":"2024-09-13T15:51:39","modified_gmt":"2027-03-02T15:51:39","slug":"cowgirls-take-sixth-at-district-tournament","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2022\/11\/03\/cowgirls-take-sixth-at-district-tournament\/?destination=northern-plains-independent","title":{"rendered":"Cowgirls Take Sixth At District Tournament"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>The Culbertson Cowgirls placed sixth at the District 1C volleyball tournament and came just one victory away from qualifying for the divisional  tournament.<br \/>\n\t  The Cowgirls lost a heartbreaking  fifth-place match against Fairview, 25-21, 22-25, 11-25, 29-27, 12-15 on Saturday, Oct. 29.<br \/>\n\t  Culbertson trailed by a 2219 margin in the fourth set but displayed great character in coming back. Kills by<\/p>\n","protected":false},"author":1,"featured_media":47208,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"news-destination":[13],"news-source":[12],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/47222"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=47222"}],"version-history":[{"count":2,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/47222\/revisions"}],"predecessor-version":[{"id":47338,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/47222\/revisions\/47338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media\/47208"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=47222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=47222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=47222"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=47222"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=47222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}