{"id":46605,"date":"2022-10-27T05:03:00","date_gmt":"2022-10-27T11:03:00","guid":{"rendered":"https:\/\/www-northernplainsindependent-com-uswp*.sitenm.com\/?p=46605?destination=northern-plains-independent"},"modified":"2024-09-13T15:51:41","modified_gmt":"2027-03-02T15:51:41","slug":"cowgirls-down-fusion-in-league-play","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2022\/10\/27\/cowgirls-down-fusion-in-league-play\/?destination=northern-plains-independent","title":{"rendered":"Cowgirls Down Fusion In League Play"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>The Culbertson Cowgirls ended their regular season with a home victory over Richey\/Lambert Fusion on Wednesday, Oct 20.<br \/>\n\t  The Cowgirls posted a 2519, 25-7, 25-16, win.<br \/>\n\t  Two kills and a block by Makena Hauge produced a quick 8-4 lead in the first set for Culbertson. After the Fusion  cut the gap to 11-9, the Cowgirls struck with a kill by Destiny Thompson and an ace by Leandra Perkins.<br \/>\n\t  An ace<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"news-destination":[13],"news-source":[12],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/46605"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=46605"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/46605\/revisions"}],"predecessor-version":[{"id":47341,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/46605\/revisions\/47341"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=46605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=46605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=46605"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=46605"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=46605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}