{"id":45839,"date":"2022-09-08T05:05:20","date_gmt":"2022-09-08T11:05:20","guid":{"rendered":"https:\/\/www-northernplainsindependent-com-uswp*.sitenm.com\/?p=45839?destination=northern-plains-independent"},"modified":"2022-09-08T08:13:04","modified_gmt":"2025-02-24T08:13:04","slug":"stabbing-suspect-on-the-run-after-attacks-in-canada","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2022\/09\/08\/stabbing-suspect-on-the-run-after-attacks-in-canada\/?destination=northern-plains-independent","title":{"rendered":"Stabbing Suspect On The  Run After Attacks In Canada"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Canadian authorities are searching for suspect Myles  Sanderson in connection with a mass stabbing Sunday that left at least 10 people dead and 15 injured across crime scenes in Saskatchewan  in central Canada.<br \/>\n\t  Two suspects, Damien Sanderson and Myles Sanderson,  brothers, were initially named. The former, Damien, was found deceased Sept. 5, according to Saskatchewan RCMP Commanding Officer  Assistant<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/45839"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=45839"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/45839\/revisions"}],"predecessor-version":[{"id":45873,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/45839\/revisions\/45873"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=45839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=45839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=45839"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=45839"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=45839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}