{"id":45788,"date":"2022-09-08T05:01:30","date_gmt":"2022-09-08T11:01:30","guid":{"rendered":"https:\/\/www-northernplainsindependent-com-uswp*.sitenm.com\/?p=45788?destination=northern-plains-independent"},"modified":"2022-09-15T08:30:47","modified_gmt":"2025-03-03T08:30:47","slug":"froid-lake-downs-brockton-in-match","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2022\/09\/08\/froid-lake-downs-brockton-in-match\/?destination=northern-plains-independent","title":{"rendered":"Froid\/Lake Downs Brockton In Match"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>The Froid\/Lake Red Hawks started league play with a 25-16, 25-3, 25-5, victory in Brockton  on Tuesday, Aug. 30.<br \/>\n\t  Baylee Davidson led the Red Hawks with 16 aces, seven  assists and one block.<br \/>\n\t  Carolyn Christoffersen finished with six kills and a block.<br \/>\n\t  Dasani Nesbit accounted for five digs.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"news-destination":[13],"news-source":[12],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/45788"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=45788"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/45788\/revisions"}],"predecessor-version":[{"id":46034,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/45788\/revisions\/46034"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=45788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=45788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=45788"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=45788"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=45788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}