{"id":45559,"date":"2022-08-25T05:05:00","date_gmt":"2022-08-25T11:05:00","guid":{"rendered":"https:\/\/www-northernplainsindependent-com-uswp*.sitenm.com\/?p=45559?destination=northern-plains-independent"},"modified":"2022-08-25T05:08:13","modified_gmt":"2025-02-10T05:08:13","slug":"library-board-discusses-strategic-plan","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2022\/08\/25\/library-board-discusses-strategic-plan\/?destination=northern-plains-independent","title":{"rendered":"Library Board Discusses  Strategic Plan"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>The Roosevelt County Library board held their regular meeting July 23 via Zoom.<br \/>\n\t  Chairperson Beth Hekkel was in attendance, as were vice-chair Joyce Harvey, trustees Helen Welte, Perry Lilley Sr., Vernice Madison and director  Janet Livingston.<br \/>\n\t  Montana State library consultant  Suzanne Reymer attended the meeting as a guest. The meeting was called to order at 10 a.m.<br \/>\n\t  The board discussed<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[47],"tags":[],"news-destination":[13],"news-source":[12],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/45559"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=45559"}],"version-history":[{"count":0,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/45559\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=45559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=45559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=45559"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=45559"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=45559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}