{"id":43406,"date":"2022-06-02T05:02:00","date_gmt":"2022-06-02T11:02:00","guid":{"rendered":"https:\/\/uswps02.newsmemory.com\/northernplainsindependent\/news\/?p=43406?destination=northern-plains-independent"},"modified":"2022-06-02T05:08:44","modified_gmt":"2024-11-18T05:08:44","slug":"christoffersen-perkins-earn-honors-at-state-meet","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2022\/06\/02\/christoffersen-perkins-earn-honors-at-state-meet\/?destination=northern-plains-independent","title":{"rendered":"Christoffersen, Perkins Earn Honors At State Meet"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>The performances of Froid\/Lake\u2019s Carolyne Christoffersen  and Culbertson\u2019s Aiden Perkins were highlights  for Roosevelt County  at the Class C state track meet held in Great Falls.<br \/>\n\t  Christoffersen, a junior, captured the state championship  in the shot put with a mark of 37-4.<br \/>\n\t  \u201cMy goal was to win,\u201d Christoffersen said. \u201cIt would had been nice to get a PR.\u201d<br \/>\n\t  Her best effort this<\/p>\n","protected":false},"author":1,"featured_media":43400,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"news-destination":[13],"news-source":[12],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/43406"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=43406"}],"version-history":[{"count":0,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/43406\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media\/43400"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=43406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=43406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=43406"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=43406"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=43406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}