{"id":41944,"date":"2022-03-24T05:03:20","date_gmt":"2022-03-24T11:03:20","guid":{"rendered":"https:\/\/uswps02.newsmemory.com\/northernplainsindependent\/news\/?p=41944?destination=northern-plains-independent"},"modified":"2022-03-24T05:23:02","modified_gmt":"2024-09-09T05:23:02","slug":"culbertson-prepares-for-upcoming-track-season","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2022\/03\/24\/culbertson-prepares-for-upcoming-track-season\/?destination=northern-plains-independent","title":{"rendered":"Culbertson Prepares For Upcoming Track Season"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Culbertson enjoys a turnout  of 28 athletes out for track this season.<br \/>\n\t  \u201cIt\u2019s a good turnout, It\u2019s about the same as last year,\u201d Culbertson Coach Dave Solem said. \u201cIt\u2019s a nice mix of older and younger kids.\u201d<br \/>\n\t  The roster is divided into 17 boys and 11 girls.<br \/>\n\t  High jump should be a strength for the Cowgirls since Megan Granbois and Makena Hauge each qualified for state in the event<\/p>\n","protected":false},"author":1,"featured_media":41933,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"news-destination":[13],"news-source":[12],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/41944"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=41944"}],"version-history":[{"count":0,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/41944\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media\/41933"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=41944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=41944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=41944"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=41944"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=41944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}