{"id":40593,"date":"2022-01-13T05:05:30","date_gmt":"2022-01-13T12:05:30","guid":{"rendered":"https:\/\/uswps02.newsmemory.com\/northernplainsindependent\/news\/?p=40593?destination=northern-plains-independent"},"modified":"2022-01-13T05:14:52","modified_gmt":"2024-11-28T05:14:52","slug":"bia-launches-site-for-missing-murdered-indigenous-persons","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2022\/01\/13\/bia-launches-site-for-missing-murdered-indigenous-persons\/?destination=northern-plains-independent","title":{"rendered":"BIA Launches Site For Missing,  Murdered Indigenous Persons"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>The Bureau of Indian Affairs  has launched a new website to assist with cases involving missing and murdered  indigenous people. Officials launched the website  last month to connect individuals with information about open cases to authorities  managing investigations. American Indian and Alaska Native people are at a disproportionate  risk of experiencing  violence, murder, or going missing. The Missing<\/p>\n","protected":false},"author":1,"featured_media":40569,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/40593"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=40593"}],"version-history":[{"count":0,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/40593\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media\/40569"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=40593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=40593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=40593"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=40593"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=40593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}