{"id":40198,"date":"2021-12-23T05:05:30","date_gmt":"2021-12-23T12:05:30","guid":{"rendered":"https:\/\/uswps02.newsmemory.com\/northernplainsindependent\/news\/?p=40198?destination=northern-plains-independent"},"modified":"2021-12-23T05:17:56","modified_gmt":"2024-11-07T05:17:56","slug":"cowgirls-defeats-bainville-squad","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2021\/12\/23\/cowgirls-defeats-bainville-squad\/?destination=northern-plains-independent","title":{"rendered":"Cowgirls Defeats Bainville Squad"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>The Culbertson Cowgirls enjoyed a strong start and earned a 61-31 basketball victory  in Bainville Friday, Dec. 17.<br \/>\n\t  The Cowgirls jumped out to a 17-4 advantage during the first quarter of the contest.<br \/>\n\t  Culbertson then accounted for 25 points in the second quarter for a 42-14 half-time advantage.<br \/>\n\t  The Cowgirls led 56-19 after  three quarters of play.<br \/>\n\t  Reaching double figures for Culbertson<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"news-destination":[13],"news-source":[12],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/40198"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=40198"}],"version-history":[{"count":0,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/40198\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=40198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=40198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=40198"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=40198"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=40198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}