{"id":40137,"date":"2021-12-23T05:02:50","date_gmt":"2021-12-23T12:02:50","guid":{"rendered":"https:\/\/uswps02.newsmemory.com\/northernplainsindependent\/news\/?p=40137?destination=northern-plains-independent"},"modified":"2021-12-23T05:09:03","modified_gmt":"2024-11-07T05:09:03","slug":"public-comment-leads-fwp-to-rethink-elk-management-proposals-20211222044526","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2021\/12\/23\/public-comment-leads-fwp-to-rethink-elk-management-proposals-20211222044526\/?destination=northern-plains-independent","title":{"rendered":"Public Comment Leads FWP To  Rethink Elk Management Proposals"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Montana Fish, Wildlife and Parks has backpedaled on a controversial elk management  strategy after a public response that FWP director Henry \u201cHank\u201d Worsech described  as a \u201cfirestorm.\u201d Even after the department backed away from the most contentious  proposal it had planned to present to the Fish and Wildlife Commission, public commenters continued to raise concerns at yesterday\u2019s commission<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"news-destination":[13],"news-source":[12],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/40137"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=40137"}],"version-history":[{"count":0,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/40137\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=40137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=40137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=40137"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=40137"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=40137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}