{"id":39650,"date":"2021-12-02T05:01:10","date_gmt":"2021-12-02T12:01:10","guid":{"rendered":"https:\/\/uswps02.newsmemory.com\/northernplainsindependent\/news\/?p=39650?destination=northern-plains-independent"},"modified":"2021-12-02T05:05:15","modified_gmt":"2024-10-17T05:05:15","slug":"childrens-story-hour-every-tuesday","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2021\/12\/02\/childrens-story-hour-every-tuesday\/?destination=northern-plains-independent","title":{"rendered":"Children\u2019s Story Hour Every Tuesday"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Culbertson Public Library\u2019s weekly story hour meets at the library on Tuesday mornings  from 10:30 to 11:30 a.m. during the school year.<br \/>\n\t  \u201cWe try to update the schedule on our Facebook page if we need to make changes,\u201d said librarian Leona Colvin. \u201cThe group is geared for children of all abilities age three and up. Each week, we sing songs, read books and do a craft or a fun activity to<\/p>\n","protected":false},"author":1,"featured_media":39641,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[13],"news-source":[12],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/39650"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=39650"}],"version-history":[{"count":0,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/39650\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media\/39641"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=39650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=39650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=39650"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=39650"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=39650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}