{"id":39505,"date":"2021-11-25T05:01:10","date_gmt":"2021-11-25T12:01:10","guid":{"rendered":"https:\/\/uswps02.newsmemory.com\/northernplainsindependent\/news\/?p=39505?destination=northern-plains-independent"},"modified":"2021-11-25T05:05:07","modified_gmt":"2024-10-10T05:05:07","slug":"roger-white-sr","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2021\/11\/25\/roger-white-sr\/?destination=northern-plains-independent","title":{"rendered":"Roger White Sr."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>\n\t Roger White Sr., 66, of Wolf Point died Nov. 20, 2021, at the Trinity Hospital.<br \/>\n\t  A wake will be held at 7 p.m. Sunday, Nov. 28, at the Frazer Community Hall. A funeral service will be held at 11 a.m. Monday, Nov. 29, at the Frazer High School. Interment  will follow at the Oswego  Presbyterian Cemetery. Clayton Stevenson Memorial  Chapel of Wolf Point was entrusted with the arrangements. <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/39505"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=39505"}],"version-history":[{"count":0,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/39505\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=39505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=39505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=39505"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=39505"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=39505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}