{"id":39402,"date":"2021-11-18T05:02:40","date_gmt":"2021-11-18T12:02:40","guid":{"rendered":"https:\/\/uswps02.newsmemory.com\/northernplainsindependent\/news\/?p=39402?destination=northern-plains-independent"},"modified":"2021-11-18T05:15:10","modified_gmt":"2024-10-03T05:15:10","slug":"red-hawks-advance-with-semi-final-win-over-big-sandy","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2021\/11\/18\/red-hawks-advance-with-semi-final-win-over-big-sandy\/?destination=northern-plains-independent","title":{"rendered":"Red Hawks Advance With Semi-final Win Over Big Sandy"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>On some days, things don\u2019t go perfectly. Those days feature  turnovers along with penalties that slow down drives. But great teams still manage to find a way to win during those challenging times.<br \/>\n\t  Despite some miscues, the Froid\/Lake advanced to its second straight second championship game by defeating  Big Sandy, 24-20, in the semi-final round in Medicine  Lake on Saturday, Nov. 13.<br \/>\n\t  \u201cThere<\/p>\n","protected":false},"author":1,"featured_media":39393,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"news-destination":[13],"news-source":[12],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/39402"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=39402"}],"version-history":[{"count":0,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/39402\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media\/39393"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=39402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=39402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=39402"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=39402"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=39402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}