{"id":39264,"date":"2021-11-11T05:04:50","date_gmt":"2021-11-11T12:04:50","guid":{"rendered":"https:\/\/uswps02.newsmemory.com\/northernplainsindependent\/news\/?p=39264?destination=northern-plains-independent"},"modified":"2021-11-11T08:11:37","modified_gmt":"2024-09-26T08:11:37","slug":"montana","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2021\/11\/11\/montana\/?destination=northern-plains-independent","title":{"rendered":"School  Menus"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Froid School Nov. 15: Chicken pot pie with biscuits.<br \/>\n\t Nov. 16: Beef stew and bosco  sticks.<br \/>\n\t Nov. 17: Meatloaf, mashed potatoes, gravy, buns, veggies  and dessert.<br \/>\n\t Nov. 18: Taco salad, refried beans and taco bar.<br \/>\n\t Nov. 19:  Fish patties on buns, chips, veggies and fruit.<br \/>\n\t ***  Culbertson School  Nov. 15:  Breakfast: Pancakes.  Lunch: Hot ham and cheese sandwiches, chicken noodle soup and<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[13],"news-source":[12],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/39264"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=39264"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/39264\/revisions"}],"predecessor-version":[{"id":39327,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/39264\/revisions\/39327"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=39264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=39264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=39264"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=39264"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=39264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}