{"id":38785,"date":"2021-10-21T05:04:00","date_gmt":"2021-10-21T11:04:00","guid":{"rendered":"https:\/\/uswps02.newsmemory.com\/northernplainsindependent\/news\/?p=38785?destination=northern-plains-independent"},"modified":"2021-10-21T05:18:58","modified_gmt":"2024-04-08T05:18:58","slug":"sister-mary-hourigan-20211020035208","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2021\/10\/21\/sister-mary-hourigan-20211020035208\/?destination=northern-plains-independent","title":{"rendered":"Sister Mary Hourigan"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Sister Mary Hourigan OP of the Dominican Sisters, Sparkill, New York, died on Oct. 11, 2021, in Siena Hall, Dominican Convent, Sparkill, N.Y. She was 87 years old.<br \/>\n\t  Born in New York City on Oct. 1, 1934, Mary was the daughter of William and Bridget Fox Hourigan. She entered the Dominican Congregation  of Our Lady of the Rosary in Sparkill on Sept. 7, 1952, and received the name Sister William Marie.<\/p>\n","protected":false},"author":1,"featured_media":38779,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/38785"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=38785"}],"version-history":[{"count":0,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/38785\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media\/38779"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=38785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=38785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=38785"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=38785"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=38785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}