{"id":38306,"date":"2021-09-30T05:03:10","date_gmt":"2021-09-30T11:03:10","guid":{"rendered":"https:\/\/uswps02.newsmemory.com\/northernplainsindependent\/news\/?p=38306?destination=northern-plains-independent"},"modified":"2021-09-30T05:21:02","modified_gmt":"2024-03-18T05:21:02","slug":"nemont-to-host-retirement-welcome-party","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2021\/09\/30\/nemont-to-host-retirement-welcome-party\/?destination=northern-plains-independent","title":{"rendered":"Nemont To Host Retirement, Welcome Party"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>A retirement\/welcome party is scheduled for Saturday,  Oct. 9, at the Stagecoach in Culbertson beginning at 4 p.m. The \u201cout with the old, in with the new\u201c event will celebrate  the retirement of Mike Machart and Jeff Thorpe and welcome two new employees to town.<br \/>\n\t  Machart and Thorpe both began working for Nemont in 1994.<br \/>\n\t  According to Mary Machart,  Mike and Jeff still had to climb telephone<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[13],"news-source":[12],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/38306"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=38306"}],"version-history":[{"count":0,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/38306\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=38306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=38306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=38306"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=38306"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=38306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}