{"id":37932,"date":"2021-09-16T05:02:50","date_gmt":"2021-09-16T11:02:50","guid":{"rendered":"https:\/\/uswps02.newsmemory.com\/northernplainsindependent\/news\/?p=37932?destination=northern-plains-independent"},"modified":"2021-09-16T05:09:15","modified_gmt":"2024-03-04T05:09:15","slug":"becker-takes-over-as-county-extension-agent","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2021\/09\/16\/becker-takes-over-as-county-extension-agent\/?destination=northern-plains-independent","title":{"rendered":"Becker Takes Over As  County Extension Agent"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>A familiar face is the new Extension agent for Roosevelt  County.<br \/>\n\t  Wendy Becker started her duties at the Extension office in Culbertson on Sept. 1. She has been the Fort Peck Extension  agent for the past 11\u00bd years.<br \/>\n\t  \u201cThe position I was in was grant-based,\u201d Becker said regarding  the job change. \u201cThat grant process has gotten more competitive.\u201d<br \/>\n\t  Becker, who graduated  from Culbertson<\/p>\n","protected":false},"author":1,"featured_media":37926,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/37932"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=37932"}],"version-history":[{"count":0,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/37932\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media\/37926"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=37932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=37932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=37932"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=37932"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=37932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}