{"id":35927,"date":"2021-06-17T05:00:40","date_gmt":"2021-06-17T11:00:40","guid":{"rendered":"https:\/\/uswps02.newsmemory.com\/northernplainsindependent\/news\/?p=35927?destination=northern-plains-independent"},"modified":"2021-06-17T05:03:40","modified_gmt":"2023-12-04T05:03:40","slug":"supreme-court-upholds-tribal-law-enforcement-authority","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2021\/06\/17\/supreme-court-upholds-tribal-law-enforcement-authority\/?destination=northern-plains-independent","title":{"rendered":"Supreme Court  Upholds Tribal Law  Enforcement Authority"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>The U.S. Supreme Court has reversed a lower court ruling limiting tribal law enforcement authority to stop and search non-Native residents. The high court\u2019s unanimous decision in United  States v. Cooley, which originated on the Crow Reservation  in southeast Montana,  was heralded as a win for tribal sovereignty and law enforcement authority.<br \/>\n\t  In the opinion issued by Justice Stephen Breyer,<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/35927"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=35927"}],"version-history":[{"count":0,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/35927\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=35927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=35927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=35927"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=35927"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=35927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}