{"id":32343,"date":"2021-02-18T05:05:10","date_gmt":"2021-02-18T12:05:10","guid":{"rendered":"https:\/\/uswps02.newsmemory.com\/northernplainsindependent\/news\/?p=32343?destination=northern-plains-independent"},"modified":"2021-02-18T05:08:04","modified_gmt":"2021-02-18T12:08:04","slug":"medicare-is-not-calling-to-update-information-20210217045732","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2021\/02\/18\/medicare-is-not-calling-to-update-information-20210217045732\/?destination=northern-plains-independent","title":{"rendered":"Medicare Is Not Calling To Update Information"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Officials have received reports  of scammers pretending  to be Medicare calling to update information over the phone. The callers ask if a person has received their new Medicare card and then ask for the number and the dates of enrollment from the card.<br \/>\n\t  They may reference real details about the cards. For instance,  one person was asked if their card was \u201cblue on the top, white in the middle,<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/32343"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=32343"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/32343\/revisions"}],"predecessor-version":[{"id":32455,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/32343\/revisions\/32455"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=32343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=32343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=32343"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=32343"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=32343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}