{"id":30389,"date":"2021-01-14T05:05:20","date_gmt":"2021-01-14T12:01:40","guid":{"rendered":"https:\/\/uswps02.newsmemory.com\/northernplainsindependent\/news\/?p=30389?destination=northern-plains-independent"},"modified":"2021-01-14T08:30:49","modified_gmt":"2021-01-14T15:30:49","slug":"lambert","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2021\/01\/14\/lambert\/?destination=northern-plains-independent","title":{"rendered":"Lady Wolves Suffer Close Defeat In Harlem"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>couple of our shots went in, we had a chance.\u201d<br \/>\n\t  Haymyanie Campbell, a junior,  scored 22 points to lead the Wolves.\u201cCampbell did an amazing job,\u201d Kolstad said. \u201cShe had multiple fastbreak layups.\u201d<br \/>\n\t  Rounding out Wolf Point\u2019s scoring were Jaylee Azure with nine, Sierra Hamilton with eight, J\u2019Elle Garfield with six, Hailey Nelson with five, Josie Kolstad with four and Joey Houg with<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/30389"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=30389"}],"version-history":[{"count":2,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/30389\/revisions"}],"predecessor-version":[{"id":30632,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/30389\/revisions\/30632"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=30389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=30389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=30389"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=30389"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=30389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}