{"id":27352,"date":"2020-11-26T05:00:30","date_gmt":"2020-11-26T12:00:30","guid":{"rendered":"https:\/\/uswps02.newsmemory.com\/northernplainsindependent\/news\/?p=27352?destination=northern-plains-independent"},"modified":"2020-11-26T05:02:08","modified_gmt":"2020-11-26T12:02:08","slug":"the-rockies-team-of-deb","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2020\/11\/26\/the-rockies-team-of-deb\/?destination=northern-plains-independent","title":{"rendered":"the Rockies team of Deb &#8230;."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>the Rockies team of Deb Albin, Barb Watson, Anne Bauer, Kimberly Richardson,  Kelly Moore, Mary Fran San Soucie, Patrick Mangan, Cami Armijo-Grover, Christopher  Coburn, JoDee Palin,  Tracy Dougher, Alison Brennan, Amy Strader, Allie Zanieri-Hale, Jenny Jo Allen and Paul Lachapelle; Jackie Rumph, agent in Yellowstone County, won the Diversity Individual award; Fergus\/Petroleum  County 4-H program assistant<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/27352"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=27352"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/27352\/revisions"}],"predecessor-version":[{"id":27476,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/27352\/revisions\/27476"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=27352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=27352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=27352"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=27352"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=27352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}