{"id":23691,"date":"2020-10-08T05:03:40","date_gmt":"2020-10-08T11:03:40","guid":{"rendered":"https:\/\/uswps02.newsmemory.com\/northernplainsindependent\/news\/?p=23691?destination=northern-plains-independent"},"modified":"2020-10-16T02:15:28","modified_gmt":"2020-10-16T08:15:28","slug":"during-fire-prevention-week-the-wolf-point-volunteer-fire-department-reminds-residents-serve-up-fire-safety-in-the-kitchen","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2020\/10\/08\/during-fire-prevention-week-the-wolf-point-volunteer-fire-department-reminds-residents-serve-up-fire-safety-in-the-kitchen\/?destination=northern-plains-independent","title":{"rendered":"During Fire Prevention Week\u2122, The Wolf Point Volunteer Fire  Department Reminds Residents: \u201cServe Up Fire Safety in the Kitchen!\u2122"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>The Wolf Point Volunteer Fire Department is teaming up with the National Fire Protection  Association\u00ae \u2014 the official sponsor of Fire Prevention  Week for more than 90 years \u2014 to promote this year\u2019s Fire Prevention Week campaign, \u201cServe Up Fire Safety in the Kitchen!\u201d<br \/>\n\t  The campaign works to educate  everyone about simple but important actions they can take to keep themselves and those<\/p>\n","protected":false},"author":1,"featured_media":24847,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/23691"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=23691"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/23691\/revisions"}],"predecessor-version":[{"id":23804,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/23691\/revisions\/23804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media\/24847"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=23691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=23691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=23691"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=23691"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=23691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}